{"id":715,"date":"2015-07-01T00:00:00","date_gmt":"2015-07-01T00:00:00","guid":{"rendered":"http:\/\/public.kiboserver.com\/perezdevargas\/la-ley-1315-boe-25062015-confirma-que-el-suelo-urbanizable-sin-ordenacion-pormenorizada-aprobada-se-valorara-como-rustico-efectos-catastrales-ibi\/"},"modified":"2019-07-10T10:07:11","modified_gmt":"2019-07-10T10:07:11","slug":"ley-1315-suelo-urbanizable-efectos-catastrales-ibi","status":"publish","type":"post","link":"https:\/\/perezdevargas.es\/es\/blog\/ley-1315-suelo-urbanizable-efectos-catastrales-ibi\/","title":{"rendered":"La Ley 13\/15 (BOE 25\/06\/2015) confirma que el suelo urbanizable sin ordenaci\u00f3n pormenorizada aprobada, se valorar\u00e1 como r\u00fastico, a efectos catastrales (IBI)."},"content":{"rendered":"<p><i><strong>\u201cPublicaci\u00f3n en el <a title=\"Reforma de la Ley Hipotecaria 13\/2'15\" href=\"https:\/\/www.boe.es\/diario_boe\/txt.php?id=BOE-A-2015-7046\" target=\"_blank\" rel=\"noopener noreferrer\">BOE de 25\/06\/2015 de la Ley 13\/2015<\/a>, de 24 de junio que reforma la Ley Hipotecaria y la Ley del Catastro Inmobiliario. El suelo urbanizable sin ordenaci\u00f3n pormenorizada aprobada, se valorar\u00e1 como r\u00fastico, a efectos catastrales. Lo que hasta ahora era un criterio jurisprudencial ha pasado a ser norma con rango de ley.\u201d<\/strong><!--more--><\/i><\/p>\n<p>1.- Con fecha 8 de agosto de 2014, publicamos un art\u00edculo de opini\u00f3n sobre la Sentencia de la Sala de lo Contencioso Administrativo del Tribunal Supremo (TS) dictada el d\u00eda 30 de mayo de 2014 en el marco de un recurso de casaci\u00f3n en inter\u00e9s de ley. Dicha resoluci\u00f3n declar\u00f3 que todos aquellos suelos que est\u00e9n clasificados en el planeamiento general como urbanizables y cuyo desarrollo dependa de la aprobaci\u00f3n del instrumento urban\u00edstico que tenga por finalidad su ordenaci\u00f3n detallada no pueden ser considerados como suelo urbano a efectos catastrales. En consecuencia, a efectos de valoraci\u00f3n catastral, deber\u00e1n tener la consideraci\u00f3n de suelo r\u00fastico. El TS interpret\u00f3 el art\u00edculo 7.2 de la Ley del Catastro Inmobiliario, que es el art\u00edculo que determina cuando un suelo debe considerarse urbano a efectos catastrales.<\/p>\n<p>En efecto, el Tribunal Supremo entiende que no cabe sostener que un suelo urbanizable, por el solo hecho de estar sectorizado, tenga la consideraci\u00f3n de urbano a efectos catastrales. De esta forma, el Alto Tribunal declara que solo pueden considerarse suelo de naturaleza urbana a efectos catastrales \u201cel suelo urbanizable sectorizado ordenado, as\u00ed como el suelo sectorizado no ordenado a partir del momento de aprobaci\u00f3n del instrumento urban\u00edstico que establezca las determinaciones para su desarrollo. Antes de ese momento, el suelo tendr\u00e1 el car\u00e1cter de r\u00fastico.\u201d<\/p>\n<p>2.- Pues bien, lo que hasta ahora era un criterio jurisprudencial ha pasado a ser norma con rango de ley. En efecto, con fecha 25 de junio de 2015 se ha publicado en el Bolet\u00edn Oficial del Estado la Ley 13\/2015, de 24 de junio que reforma tanto la Ley Hipotecaria como la Ley del Catastro Inmobiliario, que, en cuanto a la reforma de la Ley del Catastro, entr\u00f3 en vigor el d\u00eda 26 de junio. Entre las reformas introducidas en la Ley del Catastro se encuentra la modificaci\u00f3n de la letra b) del apartado 2 del art\u00edculo 7, en virtud del cual se entienden por suelo de naturaleza urbana a efectos catastrales \u201c<b><i>los terrenos que tengan la consideraci\u00f3n de urbanizables o aquellos para los que los instrumentos de ordenaci\u00f3n territorial y urban\u00edstica aprobados prevean o permitan su paso a la situaci\u00f3n de suelo urbanizado, siempre que se incluyan en sectores o \u00e1mbitos espaciales delimitados y se hayan establecido para ellos las determinaciones de ordenaci\u00f3n detallada o pormenorizada, de acuerdo con la legislaci\u00f3n urban\u00edstica aplicable<\/i><\/b>\u201d.<\/p>\n<p>De esta forma, como decimos, la Ley acoge el criterio jurisprudencial del TS indicado anteriormente.<\/p>\n<p>Teniendo en cuenta que el valor catastral sirve de base para el c\u00e1lculo de impuestos como el I.B.I. y el Impuesto sobre el Incremento de Valor de los Terrenos de naturaleza Urbana (plusval\u00eda municipal), no parece necesario dar muchas explicaciones para comprender la importancia de la modificaci\u00f3n legislativa operada. Ahora bien, tampoco puede perderse de vista que el valor catastral puede servir igualmente de base para la valoraci\u00f3n del suelo a efectos de expropiaci\u00f3n.<\/p>\n<p>3.- Para regular el cambio de clasificaci\u00f3n de los suelos urbanizables que deban tener la consideraci\u00f3n de r\u00fasticos a efectos catastrales, la Ley 13\/2015 tambi\u00e9n modifica el procedimiento simplificado de valoraci\u00f3n colectiva, lo que, a su vez, debe permitir adaptar de forma m\u00e1s \u00e1giles criterios de valor contenidos en las ponencias de valores catastrales a los cambios en las circunstancias urban\u00edsticas sin necesidad de aprobar nuevas ponencias.<\/p>\n<p>&nbsp;<\/p>\n<p>Marbella, a 1 de julio de 2015.<\/p>\n<p>P\u00e9rez de Vargas Abogados.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u201cPublicaci\u00f3n en el BOE de 25\/06\/2015 de la Ley 13\/2015, de 24 de junio que reforma la Ley Hipotecaria y [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":1235,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[7],"tags":[215,167,128,103],"class_list":["post-715","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-articulos-de-opinion","tag-catastro","tag-ibi","tag-loua","tag-urbanismo"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.2 (Yoast SEO v28.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Para el IBI es r\u00fastico un suelo sin ordenaci\u00f3n detallada aprobada<\/title>\n<meta name=\"description\" content=\"\u201cPublicaci\u00f3n en el BOE de 25\/06\/2015 de la Ley 13\/2015, de 24 de junio que reforma la Ley Hipotecaria y la Ley del Catastro Inmobiliario. El suelo\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/perezdevargas.es\/es\/blog\/ley-1315-suelo-urbanizable-efectos-catastrales-ibi\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La Ley 13\/15 (BOE 25\/06\/2015) confirma que el suelo urbanizable sin ordenaci\u00f3n pormenorizada aprobada, se valorar\u00e1 como r\u00fastico, a efectos catastrales (IBI).\" \/>\n<meta property=\"og:description\" content=\"\u201cPublicaci\u00f3n en el BOE de 25\/06\/2015 de la Ley 13\/2015, de 24 de junio que reforma la Ley Hipotecaria y la Ley del Catastro Inmobiliario. El suelo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/perezdevargas.es\/es\/blog\/ley-1315-suelo-urbanizable-efectos-catastrales-ibi\/\" \/>\n<meta property=\"og:site_name\" content=\"P\u00e9rez de Vargas\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/perezdevargasabogados\/\" \/>\n<meta property=\"article:published_time\" content=\"2015-07-01T00:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-07-10T10:07:11+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/perezdevargas.es\/wp-content\/uploads\/2015\/07\/catastro-2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"470\" \/>\n\t<meta property=\"og:image:height\" content=\"313\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Jose Castellano Fernandez\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jose Castellano Fernandez\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/perezdevargas.es\\\/es\\\/blog\\\/ley-1315-suelo-urbanizable-efectos-catastrales-ibi\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/perezdevargas.es\\\/es\\\/blog\\\/ley-1315-suelo-urbanizable-efectos-catastrales-ibi\\\/\"},\"author\":{\"name\":\"Jose Castellano Fernandez\",\"@id\":\"https:\\\/\\\/perezdevargas.es\\\/es\\\/#\\\/schema\\\/person\\\/e4e1ac674354988ec8bbe4529b1c5bc1\"},\"headline\":\"La Ley 13\\\/15 (BOE 25\\\/06\\\/2015) confirma que el suelo urbanizable sin ordenaci\u00f3n pormenorizada aprobada, se valorar\u00e1 como r\u00fastico, a efectos catastrales (IBI).\",\"datePublished\":\"2015-07-01T00:00:00+00:00\",\"dateModified\":\"2019-07-10T10:07:11+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/perezdevargas.es\\\/es\\\/blog\\\/ley-1315-suelo-urbanizable-efectos-catastrales-ibi\\\/\"},\"wordCount\":670,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/perezdevargas.es\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/perezdevargas.es\\\/es\\\/blog\\\/ley-1315-suelo-urbanizable-efectos-catastrales-ibi\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/perezdevargas.es\\\/wp-content\\\/uploads\\\/2015\\\/07\\\/catastro-2.jpg\",\"keywords\":[\"catastro\",\"IBI\",\"LOUA\",\"urbanismo\"],\"articleSection\":[\"Art\u00edculos de opini\u00f3n\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/perezdevargas.es\\\/es\\\/blog\\\/ley-1315-suelo-urbanizable-efectos-catastrales-ibi\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/perezdevargas.es\\\/es\\\/blog\\\/ley-1315-suelo-urbanizable-efectos-catastrales-ibi\\\/\",\"url\":\"https:\\\/\\\/perezdevargas.es\\\/es\\\/blog\\\/ley-1315-suelo-urbanizable-efectos-catastrales-ibi\\\/\",\"name\":\"Para el IBI es r\u00fastico un suelo sin ordenaci\u00f3n detallada aprobada\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/perezdevargas.es\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/perezdevargas.es\\\/es\\\/blog\\\/ley-1315-suelo-urbanizable-efectos-catastrales-ibi\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/perezdevargas.es\\\/es\\\/blog\\\/ley-1315-suelo-urbanizable-efectos-catastrales-ibi\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/perezdevargas.es\\\/wp-content\\\/uploads\\\/2015\\\/07\\\/catastro-2.jpg\",\"datePublished\":\"2015-07-01T00:00:00+00:00\",\"dateModified\":\"2019-07-10T10:07:11+00:00\",\"description\":\"\u201cPublicaci\u00f3n en el BOE de 25\\\/06\\\/2015 de la Ley 13\\\/2015, de 24 de junio que reforma la Ley Hipotecaria y la Ley del Catastro Inmobiliario. El suelo\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/perezdevargas.es\\\/es\\\/blog\\\/ley-1315-suelo-urbanizable-efectos-catastrales-ibi\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/perezdevargas.es\\\/es\\\/blog\\\/ley-1315-suelo-urbanizable-efectos-catastrales-ibi\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/perezdevargas.es\\\/es\\\/blog\\\/ley-1315-suelo-urbanizable-efectos-catastrales-ibi\\\/#primaryimage\",\"url\":\"https:\\\/\\\/perezdevargas.es\\\/wp-content\\\/uploads\\\/2015\\\/07\\\/catastro-2.jpg\",\"contentUrl\":\"https:\\\/\\\/perezdevargas.es\\\/wp-content\\\/uploads\\\/2015\\\/07\\\/catastro-2.jpg\",\"width\":470,\"height\":313},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/perezdevargas.es\\\/es\\\/blog\\\/ley-1315-suelo-urbanizable-efectos-catastrales-ibi\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/perezdevargas.es\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La Ley 13\\\/15 (BOE 25\\\/06\\\/2015) confirma que el suelo urbanizable sin ordenaci\u00f3n pormenorizada aprobada, se valorar\u00e1 como r\u00fastico, a efectos catastrales (IBI).\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/perezdevargas.es\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/perezdevargas.es\\\/es\\\/\",\"name\":\"P\u00e9rez de Vargas\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/perezdevargas.es\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/perezdevargas.es\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/perezdevargas.es\\\/es\\\/#organization\",\"name\":\"P\u00e9rez de Vargas\",\"url\":\"https:\\\/\\\/perezdevargas.es\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/perezdevargas.es\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/perezdevargas.es\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/Diseno-sin-titulo-91-1.jpg\",\"contentUrl\":\"https:\\\/\\\/perezdevargas.es\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/Diseno-sin-titulo-91-1.jpg\",\"width\":500,\"height\":500,\"caption\":\"P\u00e9rez de Vargas\"},\"image\":{\"@id\":\"https:\\\/\\\/perezdevargas.es\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/perezdevargasabogados\\\/\",\"https:\\\/\\\/www.instagram.com\\\/perezdevargasabogados\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/perezdevargas.es\\\/es\\\/#\\\/schema\\\/person\\\/e4e1ac674354988ec8bbe4529b1c5bc1\",\"name\":\"Jose Castellano Fernandez\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d291efb688f2393d5ffd2c4adb34666a764b3dd0f5bc2e0fdb18927b565dd5db?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d291efb688f2393d5ffd2c4adb34666a764b3dd0f5bc2e0fdb18927b565dd5db?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d291efb688f2393d5ffd2c4adb34666a764b3dd0f5bc2e0fdb18927b565dd5db?s=96&d=mm&r=g\",\"caption\":\"Jose Castellano Fernandez\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Para el IBI es r\u00fastico un suelo sin ordenaci\u00f3n detallada aprobada","description":"\u201cPublicaci\u00f3n en el BOE de 25\/06\/2015 de la Ley 13\/2015, de 24 de junio que reforma la Ley Hipotecaria y la Ley del Catastro Inmobiliario. El suelo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/perezdevargas.es\/es\/blog\/ley-1315-suelo-urbanizable-efectos-catastrales-ibi\/","og_locale":"es_ES","og_type":"article","og_title":"La Ley 13\/15 (BOE 25\/06\/2015) confirma que el suelo urbanizable sin ordenaci\u00f3n pormenorizada aprobada, se valorar\u00e1 como r\u00fastico, a efectos catastrales (IBI).","og_description":"\u201cPublicaci\u00f3n en el BOE de 25\/06\/2015 de la Ley 13\/2015, de 24 de junio que reforma la Ley Hipotecaria y la Ley del Catastro Inmobiliario. El suelo","og_url":"https:\/\/perezdevargas.es\/es\/blog\/ley-1315-suelo-urbanizable-efectos-catastrales-ibi\/","og_site_name":"P\u00e9rez de Vargas","article_publisher":"https:\/\/www.facebook.com\/perezdevargasabogados\/","article_published_time":"2015-07-01T00:00:00+00:00","article_modified_time":"2019-07-10T10:07:11+00:00","og_image":[{"width":470,"height":313,"url":"https:\/\/perezdevargas.es\/wp-content\/uploads\/2015\/07\/catastro-2.jpg","type":"image\/jpeg"}],"author":"Jose Castellano Fernandez","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Jose Castellano Fernandez","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/perezdevargas.es\/es\/blog\/ley-1315-suelo-urbanizable-efectos-catastrales-ibi\/#article","isPartOf":{"@id":"https:\/\/perezdevargas.es\/es\/blog\/ley-1315-suelo-urbanizable-efectos-catastrales-ibi\/"},"author":{"name":"Jose Castellano Fernandez","@id":"https:\/\/perezdevargas.es\/es\/#\/schema\/person\/e4e1ac674354988ec8bbe4529b1c5bc1"},"headline":"La Ley 13\/15 (BOE 25\/06\/2015) confirma que el suelo urbanizable sin ordenaci\u00f3n pormenorizada aprobada, se valorar\u00e1 como r\u00fastico, a efectos catastrales (IBI).","datePublished":"2015-07-01T00:00:00+00:00","dateModified":"2019-07-10T10:07:11+00:00","mainEntityOfPage":{"@id":"https:\/\/perezdevargas.es\/es\/blog\/ley-1315-suelo-urbanizable-efectos-catastrales-ibi\/"},"wordCount":670,"commentCount":0,"publisher":{"@id":"https:\/\/perezdevargas.es\/es\/#organization"},"image":{"@id":"https:\/\/perezdevargas.es\/es\/blog\/ley-1315-suelo-urbanizable-efectos-catastrales-ibi\/#primaryimage"},"thumbnailUrl":"https:\/\/perezdevargas.es\/wp-content\/uploads\/2015\/07\/catastro-2.jpg","keywords":["catastro","IBI","LOUA","urbanismo"],"articleSection":["Art\u00edculos de opini\u00f3n"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/perezdevargas.es\/es\/blog\/ley-1315-suelo-urbanizable-efectos-catastrales-ibi\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/perezdevargas.es\/es\/blog\/ley-1315-suelo-urbanizable-efectos-catastrales-ibi\/","url":"https:\/\/perezdevargas.es\/es\/blog\/ley-1315-suelo-urbanizable-efectos-catastrales-ibi\/","name":"Para el IBI es r\u00fastico un suelo sin ordenaci\u00f3n detallada aprobada","isPartOf":{"@id":"https:\/\/perezdevargas.es\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/perezdevargas.es\/es\/blog\/ley-1315-suelo-urbanizable-efectos-catastrales-ibi\/#primaryimage"},"image":{"@id":"https:\/\/perezdevargas.es\/es\/blog\/ley-1315-suelo-urbanizable-efectos-catastrales-ibi\/#primaryimage"},"thumbnailUrl":"https:\/\/perezdevargas.es\/wp-content\/uploads\/2015\/07\/catastro-2.jpg","datePublished":"2015-07-01T00:00:00+00:00","dateModified":"2019-07-10T10:07:11+00:00","description":"\u201cPublicaci\u00f3n en el BOE de 25\/06\/2015 de la Ley 13\/2015, de 24 de junio que reforma la Ley Hipotecaria y la Ley del Catastro Inmobiliario. El suelo","breadcrumb":{"@id":"https:\/\/perezdevargas.es\/es\/blog\/ley-1315-suelo-urbanizable-efectos-catastrales-ibi\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/perezdevargas.es\/es\/blog\/ley-1315-suelo-urbanizable-efectos-catastrales-ibi\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/perezdevargas.es\/es\/blog\/ley-1315-suelo-urbanizable-efectos-catastrales-ibi\/#primaryimage","url":"https:\/\/perezdevargas.es\/wp-content\/uploads\/2015\/07\/catastro-2.jpg","contentUrl":"https:\/\/perezdevargas.es\/wp-content\/uploads\/2015\/07\/catastro-2.jpg","width":470,"height":313},{"@type":"BreadcrumbList","@id":"https:\/\/perezdevargas.es\/es\/blog\/ley-1315-suelo-urbanizable-efectos-catastrales-ibi\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/perezdevargas.es\/es\/"},{"@type":"ListItem","position":2,"name":"La Ley 13\/15 (BOE 25\/06\/2015) confirma que el suelo urbanizable sin ordenaci\u00f3n pormenorizada aprobada, se valorar\u00e1 como r\u00fastico, a efectos catastrales (IBI)."}]},{"@type":"WebSite","@id":"https:\/\/perezdevargas.es\/es\/#website","url":"https:\/\/perezdevargas.es\/es\/","name":"P\u00e9rez de Vargas","description":"","publisher":{"@id":"https:\/\/perezdevargas.es\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/perezdevargas.es\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/perezdevargas.es\/es\/#organization","name":"P\u00e9rez de Vargas","url":"https:\/\/perezdevargas.es\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/perezdevargas.es\/es\/#\/schema\/logo\/image\/","url":"https:\/\/perezdevargas.es\/wp-content\/uploads\/2025\/04\/Diseno-sin-titulo-91-1.jpg","contentUrl":"https:\/\/perezdevargas.es\/wp-content\/uploads\/2025\/04\/Diseno-sin-titulo-91-1.jpg","width":500,"height":500,"caption":"P\u00e9rez de Vargas"},"image":{"@id":"https:\/\/perezdevargas.es\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/perezdevargasabogados\/","https:\/\/www.instagram.com\/perezdevargasabogados\/"]},{"@type":"Person","@id":"https:\/\/perezdevargas.es\/es\/#\/schema\/person\/e4e1ac674354988ec8bbe4529b1c5bc1","name":"Jose Castellano Fernandez","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/d291efb688f2393d5ffd2c4adb34666a764b3dd0f5bc2e0fdb18927b565dd5db?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/d291efb688f2393d5ffd2c4adb34666a764b3dd0f5bc2e0fdb18927b565dd5db?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d291efb688f2393d5ffd2c4adb34666a764b3dd0f5bc2e0fdb18927b565dd5db?s=96&d=mm&r=g","caption":"Jose Castellano Fernandez"}}]}},"_links":{"self":[{"href":"https:\/\/perezdevargas.es\/es\/wp-json\/wp\/v2\/posts\/715","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/perezdevargas.es\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/perezdevargas.es\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/perezdevargas.es\/es\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/perezdevargas.es\/es\/wp-json\/wp\/v2\/comments?post=715"}],"version-history":[{"count":3,"href":"https:\/\/perezdevargas.es\/es\/wp-json\/wp\/v2\/posts\/715\/revisions"}],"predecessor-version":[{"id":2367,"href":"https:\/\/perezdevargas.es\/es\/wp-json\/wp\/v2\/posts\/715\/revisions\/2367"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/perezdevargas.es\/es\/wp-json\/wp\/v2\/media\/1235"}],"wp:attachment":[{"href":"https:\/\/perezdevargas.es\/es\/wp-json\/wp\/v2\/media?parent=715"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/perezdevargas.es\/es\/wp-json\/wp\/v2\/categories?post=715"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/perezdevargas.es\/es\/wp-json\/wp\/v2\/tags?post=715"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}